{"id":1567,"date":"2021-02-07T16:53:25","date_gmt":"2021-02-07T16:53:25","guid":{"rendered":"http:\/\/a8759758b2.nxcli.io\/?p=1567"},"modified":"2026-07-05T18:48:43","modified_gmt":"2026-07-05T18:48:43","slug":"update-pro-4-1","status":"publish","type":"post","link":"https:\/\/couponaffiliates.com\/de\/update-pro-4-1\/","title":{"rendered":"Coupon Affiliates - Version 4.1! Neue flexible Provisionseinstellungen, R\u00fcckerstattungsberechnungen, Produktlisten und mehr."},"content":{"rendered":"<p class=\"wp-block-paragraph\">Nach der erfolgreichen Einf\u00fchrung von Version 4 im letzten Monat, sind wir mit einem weiteren gro\u00dfartigen Update zur\u00fcck!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit Version 4.1 wurden neue Provisionseinstellungen, bessere Berechnungen von R\u00fcckerstattungen, Produktlisten in den Tabellen der monatlichen und letzten Bestellungen sowie einige andere kleine Korrekturen eingef\u00fchrt.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Flexible Provisionseinstellungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Einer der wichtigsten Punkte dieser Aktualisierung ist die neue flexible Provision.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Erstens k\u00f6nnen Sie jetzt feste Provisionsbetr\u00e4ge sowohl \"pro Auftrag\" als auch \"pro Produkt\" festlegen, neben der bereits bestehenden Option \"Prozentsatz\" des Gesamtauftrags.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Noch besser ist, dass Sie flexiblere Provisionsberechnungen erstellen k\u00f6nnen, indem Sie alle 3 (oder 2) von ihnen kombinieren, um eine Vielzahl verschiedener Provisionskombinationen zu erhalten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Beispiel<\/strong>:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">So k\u00f6nnten Sie zum Beispiel eine Provision von 10% der Gesamtbestellung, plus $1 pro Produkt und schlie\u00dflich $5 pro Bestellung berechnen lassen. Auf diese Weise k\u00f6nnen Sie eine wirklich einzigartige, individuelle Provision auf der Grundlage Ihrer genauen Anforderungen erstellen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit den oben genannten Betr\u00e4gen, als Beispiel f\u00fcr eine Bestellung, wenn der Affiliate-Gutschein f\u00fcr eine Bestellung von \"10 x PRODUKT\" verwendet wurde, die $20 pro Produkt kostet ($200 insgesamt), w\u00fcrde die gesamte Affiliate-Provision $20 + $10 + $5 betragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Legen Sie eine individuelle Provision pro Coupon und Produkt fest:<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und das ist noch nicht alles: Sie k\u00f6nnen noch einen Schritt weiter gehen und benutzerdefinierte \"flexible Provisionsbetr\u00e4ge\" f\u00fcr einzelne Produkte oder Gutscheine festlegen, so dass diese die Standardwerte \u00fcberschreiben. Sie k\u00f6nnen auch eine Priorit\u00e4t zwischen Produkt- oder Gutscheinprovisionen w\u00e4hlen, d. h. wenn beide eingestellt sind, wird der entsprechende Provisionsbetrag verwendet. Ist keines von beiden eingestellt, wird der Standardwert verwendet.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Screenshot:<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"896\" height=\"374\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/01\/59b7265f5de16650ebb98feeba1fd18a.png\" alt=\"\" class=\"wp-image-1450\" srcset=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/01\/59b7265f5de16650ebb98feeba1fd18a.png 896w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/01\/59b7265f5de16650ebb98feeba1fd18a-300x125.png 300w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/01\/59b7265f5de16650ebb98feeba1fd18a-768x321.png 768w\" sizes=\"(max-width: 896px) 100vw, 896px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Erstattungsberechnungen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben sie jetzt aktualisiert, so dass Erstattungen bei der Berechnung und Anzeige der Provisionen ber\u00fccksichtigt werden.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Wenn eine Bestellung vollst\u00e4ndig zur\u00fcckerstattet wird, wird diese aus der noch ausstehenden Provision f\u00fcr Partner\/Coupons entfernt (sofern sie erteilt wurde).<\/li><li>Wenn eine Bestellung teilweise zur\u00fcckerstattet wird, wird die Provision f\u00fcr den zur\u00fcckerstatteten Betrag von der noch ausstehenden Provision des Partners abgezogen (falls sie gew\u00e4hrt wurde).<\/li><li>Wenn ein Auftrag von einem abgeschlossenen in einen anderen Status ge\u00e4ndert wird, wird die f\u00fcr diesen Auftrag gew\u00e4hrte Provision von der ausstehenden Provision des Partners abgezogen.<\/li><\/ul>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Produkte-Listen<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Wir haben jetzt eine neue Option hinzugef\u00fcgt, um eine Liste von Produkten und Mengen sowohl in den letzten Bestellungen als auch in den monatlichen \u00dcbersichtstabellen anzuzeigen. Diese k\u00f6nnen in den Plugin-Einstellungen aktiviert werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Screenshots:<\/strong><\/p>\n\n\n\n\n<div class=\"wp-block-eedee-block-gutenslide vertical-align-center\"><div id=\"gutenslide-q9h8xv6lf\"><div class=\"eedee-background-div\"><img decoding=\"async\" width=\"1163\" height=\"672\" class=\"wp-image-1590 swiper-zoom-target\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/monthly-summary-list.png\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" srcset=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/monthly-summary-list.png 1163w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/monthly-summary-list-300x173.png 300w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/monthly-summary-list-1024x592.png 1024w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/monthly-summary-list-768x444.png 768w\" sizes=\"(max-width: 1163px) 100vw, 1163px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1\"><\/div><\/div><div class=\"slide-content\"><\/div><\/div><\/div>\n\n\n<div class=\"wp-block-eedee-block-gutenslide vertical-align-center\"><div id=\"gutenslide-yzl0ex04z\"><div class=\"eedee-background-div\"><img decoding=\"async\" width=\"1163\" height=\"672\" class=\"wp-image-1588 swiper-zoom-target\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/recent-orders-list.png\" alt=\"\" style=\"object-fit:cover;object-position:50% 50%\" srcset=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/recent-orders-list.png 1163w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/recent-orders-list-300x173.png 300w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/recent-orders-list-1024x592.png 1024w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/recent-orders-list-768x444.png 768w\" sizes=\"(max-width: 1163px) 100vw, 1163px\" \/><div class=\"eedee-background-div__overlay\" style=\"opacity:1\"><\/div><\/div><div class=\"slide-content\"><\/div><\/div><\/div>\n\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Berechnung der Provision vor Rabatt<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Es wurde eine neue optionale Einstellung hinzugef\u00fcgt, mit der die Provision berechnet werden kann, BEVOR der Rabatt aus dem Coupon angewendet wurde. Dies war ein beliebter Wunsch von mehreren Plugin-Nutzern.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Andere \u00c4nderungen und Korrekturen<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Es wurde die M\u00f6glichkeit hinzugef\u00fcgt, die Bestellnummer und die Liste der gekauften Produkte in die E-Mail-Benachrichtigungen aufzunehmen.<\/li><li>Die allgemeine Codestruktur f\u00fcr die Provisionsberechnung wurde verbessert.<\/li><li>Einige nicht korrekt funktionierende \u00dcbersetzungen wurden korrigiert.<\/li><li>Einige andere sehr kleine Fehler wurden behoben.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Following a successful launch of version 4 last month, we&#8217;re back with another great update! Version 4.1 sees the introduction of new commission settings, better calculations of refunds, products lists in the monthly and recent orders tables, and some other small fixes. Flexible Commission Settings One of the main highlights of this update is new [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1682,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[34,18],"tags":[],"class_list":["post-1567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-updates","category-news","wpbf-post"],"taxonomy_info":{"category":[{"value":34,"label":"Plugin Update"},{"value":18,"label":"News"}]},"featured_image_src_large":["https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/02\/version-4-1-1024x322.png",1024,322,true],"author_info":{"display_name":"Elliot Sowersby","author_link":"#"},"comment_info":0,"category_info":[{"term_id":34,"name":"Plugin Update","slug":"updates","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":86,"filter":"raw","cat_ID":34,"category_count":86,"category_description":"","cat_name":"Plugin Update","category_nicename":"updates","category_parent":0},{"term_id":18,"name":"News","slug":"news","term_group":0,"term_taxonomy_id":18,"taxonomy":"category","description":"","parent":0,"count":3,"filter":"raw","cat_ID":18,"category_count":3,"category_description":"","cat_name":"News","category_nicename":"news","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts\/1567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/comments?post=1567"}],"version-history":[{"count":27,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts\/1567\/revisions"}],"predecessor-version":[{"id":2388,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts\/1567\/revisions\/2388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/media\/1682"}],"wp:attachment":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/media?parent=1567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/categories?post=1567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/tags?post=1567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}