{"id":17741,"date":"2024-03-07T22:52:46","date_gmt":"2024-03-07T22:52:46","guid":{"rendered":"http:\/\/a8759758b2.nxcli.io\/?p=17741"},"modified":"2026-07-05T18:43:18","modified_gmt":"2026-07-05T18:43:18","slug":"version-5-12-8-sicherheitskorrektur","status":"publish","type":"post","link":"https:\/\/couponaffiliates.com\/de\/version-5-12-8-security-fix\/","title":{"rendered":"Version 5.12.8 - Sicherheitskorrektur"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die Version 5.12.8 wurde ver\u00f6ffentlicht und enth\u00e4lt eine Korrektur f\u00fcr ein <a href=\"https:\/\/patchstack.com\/database\/vulnerability\/woo-coupon-usage\" target=\"_blank\" rel=\"noopener\">Sicherheitsl\u00fccke, die von Patchstack entdeckt wurde<\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bereits wenige Stunden nach Bekanntwerden des Problems haben wir eine L\u00f6sung f\u00fcr dieses Problem ver\u00f6ffentlicht.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir empfehlen, so bald wie m\u00f6glich auf diese neue Version zu aktualisieren, um die Sicherheit Ihrer Website zu gew\u00e4hrleisten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Sicherheit unseres Plugins hat f\u00fcr uns oberste Priorit\u00e4t, und wir konzentrieren uns stets auf die Entwicklung von sicherem Code. Von Zeit zu Zeit k\u00f6nnen jedoch von Forschern Schwachstellen in jeder Software, auch in unserer, entdeckt werden; in diesem Fall bem\u00fchen wir uns stets, so schnell wie m\u00f6glich einen Patch f\u00fcr unsere Nutzer zu ver\u00f6ffentlichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn Sie Fragen haben, k\u00f6nnen Sie sich gerne an uns wenden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir danken Ihnen f\u00fcr Ihr Verst\u00e4ndnis und Ihre anhaltende Unterst\u00fctzung.<\/p>","protected":false},"excerpt":{"rendered":"<p>Version 5.12.8 has been released which includes a fix for a security vulnerability that was discovered by Patchstack. We released a fix for this issue with just a few hours of being made aware of it. We suggest updating to this new version as soon as possible to help keep your website secure. The security [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17743,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[34],"tags":[],"class_list":["post-17741","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-updates","wpbf-post"],"taxonomy_info":{"category":[{"value":34,"label":"Plugin Update"}]},"featured_image_src_large":["https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/03\/5.12.8-Security-Fix.png",884,464,false],"author_info":{"display_name":"Elliot Sowersby","author_link":"#"},"comment_info":0,"category_info":[{"term_id":34,"name":"Plugin Update","slug":"updates","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":86,"filter":"raw","cat_ID":34,"category_count":86,"category_description":"","cat_name":"Plugin Update","category_nicename":"updates","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts\/17741","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/comments?post=17741"}],"version-history":[{"count":11,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts\/17741\/revisions"}],"predecessor-version":[{"id":17780,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/posts\/17741\/revisions\/17780"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/media\/17743"}],"wp:attachment":[{"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/media?parent=17741"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/categories?post=17741"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couponaffiliates.com\/de\/wp-json\/wp\/v2\/tags?post=17741"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}