{"id":17890,"date":"2024-04-25T15:51:42","date_gmt":"2024-04-25T15:51:42","guid":{"rendered":"http:\/\/a8759758b2.nxcli.io\/?p=17890"},"modified":"2026-07-05T18:43:05","modified_gmt":"2026-07-05T18:43:05","slug":"actualizacion-5-13-0","status":"publish","type":"post","link":"https:\/\/couponaffiliates.com\/es\/update-5-13-0\/","title":{"rendered":"Versi\u00f3n 5.13.0 - Integraci\u00f3n de listas de correo"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Ya est\u00e1 disponible la versi\u00f3n 5.13.0 de Coupon Affiliates.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En esta actualizaci\u00f3n hemos a\u00f1adido integraciones con varias herramientas de listas de correo de terceros, para a\u00f1adir autom\u00e1ticamente sus nuevos afiliados a una lista de correo tras el registro exitoso del afiliado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Se puede integrar con los 8 proveedores siguientes:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mailpoet<\/li>\n\n\n\n<li>Mailchimp<\/li>\n\n\n\n<li>ConvertKit<\/li>\n\n\n\n<li>MailerLite<\/li>\n\n\n\n<li>ActiveCampaign<\/li>\n\n\n\n<li>Brevo (SendInBlue)<\/li>\n\n\n\n<li>Klaviyo<\/li>\n\n\n\n<li>GetResponse<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Para empezar, ve a la p\u00e1gina de configuraci\u00f3n del complemento y, en la pesta\u00f1a \"Registros\", despl\u00e1zate hasta \"Integraciones de listas de correo\". Aqu\u00ed puedes seleccionar una integraci\u00f3n de la lista desplegable y, a continuaci\u00f3n, seguir las instrucciones proporcionadas para obtener tu clave API y otros detalles necesarios.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large border-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"485\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/b83413ac9ec0458344af49a77c7ccdf7-1024x485.png\" alt=\"Integraci\u00f3n de listas de correo\" class=\"wp-image-17891\" srcset=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/b83413ac9ec0458344af49a77c7ccdf7-1024x485.png 1024w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/b83413ac9ec0458344af49a77c7ccdf7-300x142.png 300w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/b83413ac9ec0458344af49a77c7ccdf7-768x364.png 768w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/b83413ac9ec0458344af49a77c7ccdf7-360x170.png 360w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/b83413ac9ec0458344af49a77c7ccdf7.png 1126w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez configurados estos ajustes, cada vez que se a\u00f1ada un nuevo afiliado a trav\u00e9s del formulario de registro de afiliados, o que un administrador lo a\u00f1ada manualmente y lo acepte, sus datos se a\u00f1adir\u00e1n autom\u00e1ticamente a tu lista de correo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta funci\u00f3n es especialmente \u00fatil para suscribir a afiliados a una serie de correos electr\u00f3nicos de bienvenida con consejos y recursos que les ayuden en sus esfuerzos de marketing de afiliaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bfDesea solicitar alguna funci\u00f3n? No dude en <a href=\"https:\/\/roadmap.couponaffiliates.com\/boards\/feature-requests\/\">env\u00ede una sugerencia aqu\u00ed<\/a>!<\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00e1s de 4.700 sitios de WooCommerce utilizan Coupon Affiliates para crear exitosos programas de afiliaci\u00f3n. Echa un vistazo a la&nbsp;<a href=\"https:\/\/wordpress.org\/plugins\/woo-coupon-usage\/\" target=\"_blank\" rel=\"noopener\">versi\u00f3n gratuita<\/a>&nbsp;u obtener el&nbsp;<a href=\"https:\/\/couponaffiliates.com\/es\/precios\/\" target=\"_blank\" rel=\"noreferrer noopener\">versi\u00f3n premium (con 7 d\u00edas de prueba gratuita)<\/a>&nbsp;hoy.<\/p>","protected":false},"excerpt":{"rendered":"<p>Version 5.13.0 of Coupon Affiliates is now available! In this update we have added integrations with several third-party mailing list tools, to automatically add your new affiliates to a mailing list upon successful affiliate registration. The following 8 providers are available to integrate with: To get started, simply go to the plugin settings page, and [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":17901,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[34],"tags":[],"class_list":["post-17890","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-updates","wpbf-post"],"taxonomy_info":{"category":[{"value":34,"label":"Plugin Update"}]},"featured_image_src_large":["https:\/\/couponaffiliates.com\/wp-content\/uploads\/2024\/04\/Version-5.13.0-\u2013-Mailing-List-Integrations.png",884,464,false],"author_info":{"display_name":"Elliot Sowersby","author_link":"#"},"comment_info":0,"category_info":[{"term_id":34,"name":"Plugin Update","slug":"updates","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":86,"filter":"raw","cat_ID":34,"category_count":86,"category_description":"","cat_name":"Plugin Update","category_nicename":"updates","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/17890","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/comments?post=17890"}],"version-history":[{"count":9,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/17890\/revisions"}],"predecessor-version":[{"id":17903,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/17890\/revisions\/17903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/media\/17901"}],"wp:attachment":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/media?parent=17890"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/categories?post=17890"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/tags?post=17890"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}