{"id":21369,"date":"2025-07-02T21:12:32","date_gmt":"2025-07-02T21:12:32","guid":{"rendered":"https:\/\/couponaffiliates.com\/?p=21369"},"modified":"2026-07-05T18:41:54","modified_gmt":"2026-07-05T18:41:54","slug":"actualizacion-6-4-0","status":"publish","type":"post","link":"https:\/\/couponaffiliates.com\/es\/update-6-4-0\/","title":{"rendered":"Versi\u00f3n 6.4.0 - Widget flotante de afiliaci\u00f3n"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Nos complace anunciar una importante novedad para Coupon Affiliates, el&nbsp;<strong>Widget flotante de afiliaci\u00f3n<\/strong>!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta adici\u00f3n hace que sea m\u00e1s f\u00e1cil que nunca para los afiliados acceder a los enlaces de referencia, estad\u00edsticas y m\u00e1s, directamente desde cualquier p\u00e1gina de su sitio.<\/p>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"wpbf-responsive-embed\"><iframe title=\"Cup\u00f3n Afiliados: Widget flotante de afiliados\" width=\"1200\" height=\"675\" src=\"https:\/\/www.youtube.com\/embed\/O0BMqNyKLbE?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/couponaffiliates.com\/es\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfQu\u00e9 es el widget flotante de afiliaci\u00f3n?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">El Widget Flotante de Afiliado es una ventana emergente compacta y personalizable que aparece como un bot\u00f3n flotante en su sitio web.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los afiliados existentes, al hacer clic en el bot\u00f3n, se proporciona acceso instant\u00e1neo a una versi\u00f3n compacta de su panel de afiliaci\u00f3n. Mostrar\u00e1 algunas de las estad\u00edsticas y funciones m\u00e1s importantes del panel, como el cup\u00f3n y los enlaces de referencia, las estad\u00edsticas de referencia, los pedidos remitidos recientemente, los detalles de los pagos y las creatividades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para los afiliados potenciales, es una invitaci\u00f3n a unirse a su programa. Cuando hacen clic en el bot\u00f3n, acceden r\u00e1pidamente al formulario de inscripci\u00f3n. Tambi\u00e9n puede mostrar una secci\u00f3n de \"ventajas\" personalizable en el widget que explique lo que ofrece su programa de afiliaci\u00f3n.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Caracter\u00edsticas principales<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Acceso r\u00e1pido:<\/strong>&nbsp;Los afiliados pueden ver su c\u00f3digo de cup\u00f3n, enlaces de referencia y estad\u00edsticas desde cualquier lugar de su sitio.<\/li>\n\n\n\n<li><strong>Interfaz con pesta\u00f1as:<\/strong>&nbsp;El widget incluye pesta\u00f1as para enlaces de referencia, estad\u00edsticas, pedidos recientes, pagos y creatividades.<\/li>\n\n\n\n<li><strong>Herramientas de referencia:<\/strong>&nbsp;Copie f\u00e1cilmente los enlaces de referencia, genere URL cortas y comp\u00e1rtalas a trav\u00e9s de las redes sociales o c\u00f3digos QR.<\/li>\n\n\n\n<li><strong>Estad\u00edsticas en directo:<\/strong>&nbsp;Los afiliados pueden controlar en tiempo real los pedidos, las comisiones, las ventas, los descuentos, los clics y las tasas de conversi\u00f3n.<\/li>\n\n\n\n<li><strong>Pedidos recientes:<\/strong>&nbsp;Vea los \u00faltimos pedidos remitidos, incluidas las comisiones obtenidas y el estado del pedido.<\/li>\n\n\n\n<li><strong>Pago de comisiones:<\/strong>\u00a0Realice el seguimiento de las comisiones impagadas, solicite pagos y consulte los pagos recientes.<\/li>\n\n\n\n<li><strong>Biblioteca de creativos:<\/strong>\u00a0Acceda a banners, im\u00e1genes, v\u00eddeos y colores de marca para facilitar la promoci\u00f3n.<\/li>\n\n\n\n<li><strong>Dise\u00f1o adaptable:<\/strong>&nbsp;El widget est\u00e1 optimizado tanto para ordenadores de sobremesa como para dispositivos m\u00f3viles.<\/li>\n\n\n\n<li><strong>Personalizable:<\/strong>&nbsp;Los administradores pueden configurar la posici\u00f3n, el color y el tama\u00f1o de los widgets, as\u00ed como las pesta\u00f1as y funciones que se activan.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">\u00bfC\u00f3mo funciona?<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Una vez activado en la configuraci\u00f3n del plugin, el widget aparece como un bot\u00f3n flotante en su sitio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los afiliados pueden:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Seleccione su cup\u00f3n (si tiene varios)<\/li>\n\n\n\n<li>Copia su c\u00f3digo de cup\u00f3n<\/li>\n\n\n\n<li>Generar y copiar enlaces de referencia para cualquier p\u00e1gina<\/li>\n\n\n\n<li>Compartir enlaces a trav\u00e9s de Facebook, Twitter, WhatsApp, etc.<\/li>\n\n\n\n<li>Genera y descarga c\u00f3digos QR para compartirlos sin conexi\u00f3n<\/li>\n\n\n\n<li>Ver sus estad\u00edsticas y pedidos recientes<\/li>\n\n\n\n<li>Acceso a pagos y creatividades<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Todo esto est\u00e1 disponible sin salir de la p\u00e1gina actual, lo que proporciona una experiencia fluida a sus afiliados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El widget flotante se puede utilizar para cualquier tipo de programa de afiliaci\u00f3n, pero es especialmente adecuado para programas del estilo \"Recomienda a un amigo\", en los que se desea ofrecer una experiencia m\u00e1s compacta y sencilla a los usuarios afiliados.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">C\u00f3mo activar<\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Ir a\u00a0<strong>Cup\u00f3n Afiliados &gt; Configuraci\u00f3n &gt; Widget<\/strong>\u00a0en la administraci\u00f3n de WordPress.<\/li>\n\n\n\n<li>Habilite el Widget de Afiliaci\u00f3n Flotante y configure sus opciones.<\/li>\n\n\n\n<li>Guarde los cambios. El widget aparecer\u00e1 ahora en su sitio para los usuarios que cumplan los requisitos.<\/li>\n<\/ol>","protected":false},"excerpt":{"rendered":"<p>We&#8217;re excited to announce a major new feature for Coupon Affiliates, the&nbsp;Floating Affiliate Widget! This addition makes it easier than ever for affiliates to access referral links, statistics, and more, right from any page on your site. What is the Floating Affiliate Widget? The Floating Affiliate Widget is a compact, customizable popup that appears as [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21383,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[34],"tags":[],"class_list":["post-21369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-updates","wpbf-post"],"taxonomy_info":{"category":[{"value":34,"label":"Plugin Update"}]},"featured_image_src_large":["https:\/\/couponaffiliates.com\/wp-content\/uploads\/2025\/07\/Version-6.4.0-Floating-Affiliate-Widget.png",884,464,false],"author_info":{"display_name":"Elliot Sowersby","author_link":"#"},"comment_info":0,"category_info":[{"term_id":34,"name":"Plugin Update","slug":"updates","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":86,"filter":"raw","cat_ID":34,"category_count":86,"category_description":"","cat_name":"Plugin Update","category_nicename":"updates","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/21369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/comments?post=21369"}],"version-history":[{"count":5,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/21369\/revisions"}],"predecessor-version":[{"id":21389,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/posts\/21369\/revisions\/21389"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/media\/21383"}],"wp:attachment":[{"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/media?parent=21369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/categories?post=21369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couponaffiliates.com\/es\/wp-json\/wp\/v2\/tags?post=21369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}