{"id":2568,"date":"2021-03-15T18:59:05","date_gmt":"2021-03-15T18:59:05","guid":{"rendered":"http:\/\/a8759758b2.nxcli.io\/?p=2568"},"modified":"2026-07-05T18:47:39","modified_gmt":"2026-07-05T18:47:39","slug":"update-pro-4-4-2","status":"publish","type":"post","link":"https:\/\/couponaffiliates.com\/fr\/update-pro-4-4-2\/","title":{"rendered":"Coupon Affiliates - Version 4.4.2 - Rafra\u00eechissement du bouton de statistiques, formulaire de connexion, nouvelle section de param\u00e8tres \"Pro Addons\", et petites modifications \/ corrections."},"content":{"rendered":"<p class=\"wp-block-paragraph\">La version 4.4.2 de Coupon Affiliates pour WooCommerce est maintenant disponible.<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Bouton d'actualisation des statistiques<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ajout d'un bouton \"rafra\u00eechir les statistiques\" sur la page du tableau de bord des affili\u00e9s (lorsque la fonction ajax est activ\u00e9e).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cliquant sur ce bouton, toutes les statistiques seront actualis\u00e9es (avec les nouvelles commandes), sans qu'il soit n\u00e9cessaire de recharger ou d'actualiser la page.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemple :<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"468\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/gif-2-3768a28a16ff.gif\" alt=\"\" class=\"wp-image-2569\"\/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Formulaire de connexion<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Ajout d'un formulaire de connexion \u00e0 la page du tableau de bord des affili\u00e9s lorsque les utilisateurs sont d\u00e9connect\u00e9s. Peut \u00eatre d\u00e9sactiv\u00e9 dans les param\u00e8tres Pro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Exemple de capture d'\u00e9cran :<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"301\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/3a7f87f415a7cad88d71e11277f589a6-1024x301.png\" alt=\"\" class=\"wp-image-2571\" srcset=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/3a7f87f415a7cad88d71e11277f589a6-1024x301.png 1024w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/3a7f87f415a7cad88d71e11277f589a6-300x88.png 300w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/3a7f87f415a7cad88d71e11277f589a6-768x226.png 768w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/3a7f87f415a7cad88d71e11277f589a6.png 1203w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Nouvelle section des param\u00e8tres \"Pro<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Mise \u00e0 jour du design de la section \"Pro\" dans la zone de param\u00e9trage du plugin. Changement du nom de la section en \"Pro Addons\".<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Capture d'\u00e9cran :<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/9312fdfc254efbc91d042c1c63ff74ba-1024x561.png\" alt=\"\" class=\"wp-image-2570\" width=\"805\" height=\"440\" srcset=\"https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/9312fdfc254efbc91d042c1c63ff74ba-1024x561.png 1024w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/9312fdfc254efbc91d042c1c63ff74ba-300x164.png 300w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/9312fdfc254efbc91d042c1c63ff74ba-768x420.png 768w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/9312fdfc254efbc91d042c1c63ff74ba-1536x841.png 1536w, https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/9312fdfc254efbc91d042c1c63ff74ba.png 1631w\" sizes=\"(max-width: 805px) 100vw, 805px\" \/><\/figure>\n\n\n\n<hr class=\"wp-block-separator is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Autres modifications et corrections<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Mise \u00e0 jour : Chargement des statistiques sur les URL de r\u00e9f\u00e9rence via ajax (apr\u00e8s le chargement de la page). Peut \u00eatre mis \u00e0 jour avec le bouton \"refresh stats\".<\/li><li>Mise \u00e0 jour (PRO) : Chargement de la section des paiements via ajax (apr\u00e8s le chargement de la page). Peut \u00eatre mis \u00e0 jour avec le bouton \"rafra\u00eechir les statistiques\".<\/li><li>Ajustement : Ajout d'un message sur la page d'accueil du tableau de bord de l'affili\u00e9, lorsque l'utilisateur n'est assign\u00e9 \u00e0 aucun coupon.<\/li><li>Correction : Petites corrections de style pour les filtres et les boutons sur certains sites.<\/li><li>Correction : Petite correction de style sur l'espacement des cellules du tableau des commandes sur certains sites.<\/li><li>Correction : Correction du bouton \"Demander un paiement\" affichant parfois plus de 2 d\u00e9cimales.<\/li><li>Correction : Correction de quelques liens cass\u00e9s dans la zone d'administration du plugin pour les sites sur un domaine de sous-r\u00e9pertoire.<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Version 4.4.2.1 - 16 mars 2021<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Am\u00e9lioration : Le nombre d'utilisation totale a \u00e9t\u00e9 modifi\u00e9 afin d'\u00eatre plus pr\u00e9cis et de n'afficher que le nombre de commandes \"termin\u00e9es\".<\/li><li>Ajustement : Le style des graphiques lin\u00e9aires a \u00e9t\u00e9 l\u00e9g\u00e8rement modifi\u00e9.<\/li><li>Correction : Correction de l'alignement des ic\u00f4nes de statistiques sur certains sites web (centrage vertical).<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Version 4.4.2.2 - 18 mars 2021<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Ajustement : Suppression de certains codes inutiles dans le tableau de bord, ce qui permettra d'am\u00e9liorer l\u00e9g\u00e8rement la vitesse.<\/li><\/ul>","protected":false},"excerpt":{"rendered":"<p>Version 4.4.2 of Coupon Affiliates for WooCommerce is now available. Refresh Stats Button Added a &#8220;refresh stats&#8221; button to affiliate dashboard page (when ajax is enabled). Clicking this will refresh all stats (with any new orders), without having to actually reload\/refresh the page. Example: Login Form Added login form to affiliate dashboard page when users [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2569,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","footnotes":"","_links_to":"","_links_to_target":""},"categories":[34],"tags":[],"class_list":["post-2568","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-updates","wpbf-post"],"taxonomy_info":{"category":[{"value":34,"label":"Plugin Update"}]},"featured_image_src_large":["https:\/\/couponaffiliates.com\/wp-content\/uploads\/2021\/03\/gif-2-3768a28a16ff.gif",800,468,false],"author_info":{"display_name":"Elliot Sowersby","author_link":"#"},"comment_info":0,"category_info":[{"term_id":34,"name":"Plugin Update","slug":"updates","term_group":0,"term_taxonomy_id":34,"taxonomy":"category","description":"","parent":0,"count":86,"filter":"raw","cat_ID":34,"category_count":86,"category_description":"","cat_name":"Plugin Update","category_nicename":"updates","category_parent":0}],"tag_info":false,"_links":{"self":[{"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/2568","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/comments?post=2568"}],"version-history":[{"count":11,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/2568\/revisions"}],"predecessor-version":[{"id":2743,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/posts\/2568\/revisions\/2743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/media\/2569"}],"wp:attachment":[{"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/media?parent=2568"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/categories?post=2568"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/couponaffiliates.com\/fr\/wp-json\/wp\/v2\/tags?post=2568"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}